{"id":5341,"date":"2021-01-18T22:37:31","date_gmt":"2021-01-18T22:37:31","guid":{"rendered":"https:\/\/lawbelize.bz\/?p=5341"},"modified":"2021-01-18T22:37:31","modified_gmt":"2021-01-18T22:37:31","slug":"chat-with-an-expat-richard-price-de-premium-wines-spirits","status":"publish","type":"post","link":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/","title":{"rendered":"Chat with an Expat &#8211; Richard Price de Premium Wines &#038; Spirits"},"content":{"rendered":"<p>Richard Price abri\u00f3 Premium Wines &amp; Spirits en Belice en 1995, hoy es el principal importador y distribuidor de una amplia selecci\u00f3n de vinos y licores en el pa\u00eds. En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir el negocio familiar en ese entonces.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wrobel &amp; Co:<\/strong> \u00bfCu\u00e1ndo se mud\u00f3 a Belice y por qu\u00e9 decidi\u00f3 mudarse aqu\u00ed? \u00bfQu\u00e9 le hizo dar el paso?<\/p>\n<p><strong>Richard Price:<\/strong> Me mud\u00e9 a Belice en octubre de 1986 para tener la oportunidad de crear mi propio negocio (un restaurante), con la intenci\u00f3n original de quedarme dos a\u00f1os y luego regresar al Reino Unido y hacer lo mismo all\u00ed. El costo de iniciar mi propio negocio en el Reino Unido era simplemente demasiado alto para m\u00ed. Adem\u00e1s de esto, mi padre, que hab\u00eda servido en la Real Fuerza A\u00e9rea Brit\u00e1nica, se mud\u00f3 a Belice a mediados de la d\u00e9cada de los 70, por lo que lo visit\u00e9 varias veces en vacaciones durante un per\u00edodo de diez a\u00f1os.<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfA qu\u00e9 te dedicabas en el Reino Unido?<\/p>\n<p><strong>Price:<\/strong> Soy originario de Reino Unido, aunque viv\u00ed en diferentes pa\u00edses del mundo debido a que mi padre estaba en el ej\u00e9rcito de Reino Unido. Yo estaba involucrado en el negocio de los restaurantes en Londres, despu\u00e9s de graduarme de la \u201cUniversity College Cardiff\u201d en 1982.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5305\" src=\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/how-to-open-business-in-Belize-300x169.jpg\" alt=\"Richard Price - wine price Belize opening a business in Belize\" width=\"300\" height=\"169\" \/><\/p>\n<p><strong>W &amp; C:<\/strong> Usted es propietario de Premium Wines &amp; Spirits desde 1995, \u00bfc\u00f3mo fue el proceso de establecer una empresa en Belice? \u00bfQu\u00e9 tipo de obst\u00e1culos experiment\u00f3, si los hubo? Por favor comparta con nuestros lectores consejos y cosas que debe tener en cuenta.<\/p>\n<p><strong>Price: <\/strong>Empec\u00e9 PWAS el 1 de abril de 1995, exactamente ocho a\u00f1os despu\u00e9s de abrir mi restaurante. El proceso fue extremadamente f\u00e1cil ya que era un propietario \u00fanico y requer\u00eda muy poca burocracia. Una licencia comercial obtenida del Ayuntamiento, as\u00ed como una licencia de licor y el registro del nombre comercial era todo lo que se requer\u00eda para comenzar a funcionar. Un proceso muy sencillo para iniciar lo que entonces era una peque\u00f1a empresa.<\/p>\n<p><strong>W&amp;C:<\/strong> \u00bfQu\u00e9 habr\u00eda hecho de otra manera?<\/p>\n<p><strong>Price: <\/strong>Para ser honesto, no estoy seguro de querer cambiar algo. El aprendizaje es parte de lo que hace que trabajar como independiente sea tan divertido.<\/p>\n<p><strong>W&amp;C:<\/strong> \u00bfCu\u00e1les son las principales diferencias en lo que respecta a abrir y administrar una empresa en Belice frente a abrir y administrar una empresa en el Reino Unido?<\/p>\n<p><strong>Price:<\/strong> Todo es mucho m\u00e1s simple y menos complicado, sin mencionar que es significativamente menos costoso, especialmente porque casi todo se puede hacer en l\u00ednea ahora. Si bien los contratos son obviamente una necesidad empresarial; Prefiero el viejo adagio de un apret\u00f3n de manos y la confianza mutua. Debido a que Belice es un pa\u00eds tan peque\u00f1o, no se necesita mucho tiempo para conocer a la mayor\u00eda de la comunidad empresarial y, por extensi\u00f3n, las personas y sus negocios desarrollan una reputaci\u00f3n, tanto buena como mala, muy r\u00e1pidamente.<\/p>\n<p><strong>W&amp;C: <\/strong>\u00bfRecomienda contratar a un abogado para empresas comerciales en Belice? Si es as\u00ed, \u00bfpor qu\u00e9 o por qu\u00e9 no?<\/p>\n<p><strong>Price:<\/strong> Definitivamente es ideal tener conocimiento de un abogado profesional y confiable que pueda ayudar o guiar en asuntos, ya sean comerciales, inmobiliarios o relacionados con la inmigraci\u00f3n. Si bien las solicitudes de permisos de residencia y trabajo se pueden realizar por cuenta propia, sin duda, ser\u00e1 m\u00e1s r\u00e1pido y menos estresante que un abogado lo haga por usted. Tambi\u00e9n puede ahorrarle muchos viajes a la capital, Belmop\u00e1n, donde se procesa la mayor parte de este tipo de cosas.<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfPor qu\u00e9 eligi\u00f3 abrir su negocio en la ciudad de Belice?<\/p>\n<p><strong>Price: <\/strong>Eleg\u00ed abrir mi tienda en la ciudad de Belice y aunque ya no es la capital de Belice, sigue siendo en gran medida el centro de negocios del pa\u00eds. Al ser un importador de vinos y licores, el principal puerto del pa\u00eds est\u00e1 en la ciudad de Belice, por lo que esto facilita el proceso. Tambi\u00e9n es central para distribuir al norte, oeste, sur y las islas de Belice. A la fecha ya he abierto una sucursal en Belmopan y otra en la principal isla tur\u00edstica de San Pedro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5306\" src=\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/expat-opens-liquor-business-Belize-249x300.jpg\" alt=\"Richard Price - wine price Belize opening a business in Belize\" width=\"249\" height=\"300\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfAnimal favorito en Belice?<\/p>\n<p><strong>Price: <\/strong>Mono aullador. Parece que donde quiera que uno este en Belice, se puede escuchar el distintivo llamado del mono aullador.<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfBebida favorita en Belice?<\/p>\n<p><strong>Price:<\/strong>\u00a1Vino, por supuesto!<\/p>\n<p><strong>W&amp;C:<\/strong> \u00e9poca favorita del a\u00f1o en Belice y \u00bfpor qu\u00e9?<\/p>\n<p><strong>Price: <\/strong>La mejor \u00e9poca del a\u00f1o es de marzo a mayo, cuando el clima es mayormente seco y casi siempre llega un viento refrescante procedente del mar. Esto lo hace perfecto para navegar, lo que trato de hacer la mayor\u00eda de los fines de semana, saliendo a los Cayos.<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfD\u00f3nde est\u00e1 su lugar favorito en Belice y por qu\u00e9?<\/p>\n<p><strong>Price: <\/strong>voy a los Cayos todos los meses, pero adem\u00e1s de eso, especialmente durante el \u00faltimo a\u00f1o de Covid 19, he aprovechado la oportunidad de viajar extensamente por todo el pa\u00eds y visitar centros tur\u00edsticos tanto en el interior como cerca al mar. Todos ofrecen excelentes ofertas para los residentes.<\/p>\n<p><strong>W&amp;C:<\/strong> \u00bfD\u00f3nde pueden ir las personas para obtener m\u00e1s informaci\u00f3n sobre usted y lo que hace o sobre su negocio?<\/p>\n<p><strong>Price:<\/strong> Tenemos una presencia muy activa en las redes sociales tanto en Facebook (@premiumwinesandspirits) como en Instagram (@premiumwinessp), donde siempre publicamos ofertas especiales de vinos y licores.<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfPuede explicarnos sus interacciones con Wrobel &amp; Co. y, m\u00e1s espec\u00edficamente, con nuestro socio gerente Ryan Wrobel? \u00bfCree que nuestra oficina tiene algo que ofrecer a sus clientes?<\/p>\n<p><strong>Price:<\/strong> Conozco al Sr. Wrobel desde hace muchos a\u00f1os, tanto a nivel social \/ de amistad como como socio comercial. Ambos hemos estado activos en la comunidad empresarial, incluido el servicio en la junta de la Royal British Legion (sucursal de Belice).<\/p>\n<p><strong>W &amp; C:<\/strong> \u00bfCu\u00e1les son algunas de las cosas maravillosas que le ha brindado vivir en Belice?<\/p>\n<p><strong>Price: <\/strong>La calidad de vida de vivir en Belice es incre\u00edble y \u00fanica. Tenemos f\u00e1cil acceso al mar y a los Cayos, as\u00ed como a la majestuosidad y belleza de la selva y ruinas mayas.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>\u00bfInteresado en jubilarse o reubicarse en Belice como lo hizo Richard? Contactenos <a href=\"https:\/\/lawbelize.bz\/es\/contact-us-2\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wrobel &amp; Co, Abogados de Belice<\/a>, y le ayudaremos hoy mismo a iniciar su proceso para jubilase o reubicarse en Belice.<\/p>\n<p>Para conocer m\u00e1s sobre jubilarse en Belice, visite nuestra p\u00e1gina de <a href=\"https:\/\/lawbelize.bz\/es\/preguntas-mas-frecuentes-jubilacion-en-belice-por-abogados-de-belice\/\" target=\"_blank\" rel=\"noopener noreferrer\">Preguntas Frecuentes aqu\u00ed<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><em>Esta informaci\u00f3n se proporcion\u00f3 como cortes\u00eda de los abogados de Wrobel &amp; Co. Est\u00e1 destinado a informar, no a aconsejar. Nadie debe intentar interpretar o aplicar ninguna ley sin la asistencia de un abogado. Haga clic\u00a0<a href=\"https:\/\/lawbelize.bz\/belize-attorney-disclaimer-privacy-policy\/\">aqu\u00ed<\/a>\u00a0para ver el descargo de responsabilidad completo.<\/em><\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Richard Price abri\u00f3 Premium Wines &amp; Spirits en Belice en 1995, hoy es el principal importador y distribuidor de una amplia selecci\u00f3n de vinos y licores en el pa\u00eds. En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir el negocio familiar en ese entonces. &nbsp; Wrobel &amp; Co: \u00bfCu\u00e1ndo se mud\u00f3 a Belice [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[275,110,260],"tags":[363,102,361,359],"class_list":["post-5341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-jubilacion-en-belice","category-mudarse-a-belice","tag-abogado-en-belice","tag-jubilacion","tag-negocio-en-belice","tag-retirarse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chat with an Expat - Richard Price de Premium Wines &amp; Spirits -<\/title>\n<meta name=\"description\" content=\"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chat with an Expat - Richard Price de Premium Wines &amp; Spirits -\" \/>\n<meta property=\"og:description\" content=\"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\" \/>\n<meta property=\"og:site_name\" content=\"Wrobel &amp; Co. Belize Attorneys at-law\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-18T22:37:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Miller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Miller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\"},\"author\":{\"name\":\"James Miller\",\"@id\":\"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8\"},\"headline\":\"Chat with an Expat &#8211; Richard Price de Premium Wines &#038; Spirits\",\"datePublished\":\"2021-01-18T22:37:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\"},\"wordCount\":1199,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg\",\"keywords\":[\"Abogado en Belice\",\"jubilacion\",\"Negocio en Belice\",\"Retirarse\"],\"articleSection\":[\"covid-19\",\"jubilaci\u00f3n en Belice\",\"mudarse a belice\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\",\"url\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\",\"name\":\"Chat with an Expat - Richard Price de Premium Wines & Spirits -\",\"isPartOf\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg\",\"datePublished\":\"2021-01-18T22:37:31+00:00\",\"author\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8\"},\"description\":\"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.\",\"breadcrumb\":{\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage\",\"url\":\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg\",\"contentUrl\":\"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg\",\"width\":900,\"height\":601,\"caption\":\"bunches of cork - wine price Belize opening a business in Belize\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lawbelize.bz\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat with an Expat &#8211; Richard Price de Premium Wines &#038; Spirits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lawbelize.bz\/es\/#website\",\"url\":\"https:\/\/lawbelize.bz\/es\/\",\"name\":\"Wrobel &amp; Co. Belize Attorneys at-law\",\"description\":\"Belize Lawyers | Belize Law Firm\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lawbelize.bz\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8\",\"name\":\"James Miller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g\",\"caption\":\"James Miller\"},\"url\":\"https:\/\/lawbelize.bz\/es\/author\/james\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chat with an Expat - Richard Price de Premium Wines & Spirits -","description":"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/","og_locale":"es_ES","og_type":"article","og_title":"Chat with an Expat - Richard Price de Premium Wines & Spirits -","og_description":"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.","og_url":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/","og_site_name":"Wrobel &amp; Co. Belize Attorneys at-law","article_published_time":"2021-01-18T22:37:31+00:00","og_image":[{"width":900,"height":601,"url":"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg","type":"image\/jpeg"}],"author":"James Miller","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"James Miller","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#article","isPartOf":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/"},"author":{"name":"James Miller","@id":"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8"},"headline":"Chat with an Expat &#8211; Richard Price de Premium Wines &#038; Spirits","datePublished":"2021-01-18T22:37:31+00:00","mainEntityOfPage":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/"},"wordCount":1199,"commentCount":0,"image":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage"},"thumbnailUrl":"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg","keywords":["Abogado en Belice","jubilacion","Negocio en Belice","Retirarse"],"articleSection":["covid-19","jubilaci\u00f3n en Belice","mudarse a belice"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/","url":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/","name":"Chat with an Expat - Richard Price de Premium Wines & Spirits -","isPartOf":{"@id":"https:\/\/lawbelize.bz\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage"},"image":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage"},"thumbnailUrl":"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg","datePublished":"2021-01-18T22:37:31+00:00","author":{"@id":"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8"},"description":"En esta charla con un expatriado, Richard comparte c\u00f3mo fue abrir su negocioen Belice y por qu\u00e9 Belice es el lugar ideal para vivir y empezar un negocio.","breadcrumb":{"@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#primaryimage","url":"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg","contentUrl":"https:\/\/lawbelize.bz\/wp-content\/uploads\/2021\/01\/Belize-wine-shop-wine-Belize-open-business-in-Belize.jpeg","width":900,"height":601,"caption":"bunches of cork - wine price Belize opening a business in Belize"},{"@type":"BreadcrumbList","@id":"https:\/\/lawbelize.bz\/es\/2021\/01\/18\/chat-with-an-expat-richard-price-de-premium-wines-spirits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lawbelize.bz\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Chat with an Expat &#8211; Richard Price de Premium Wines &#038; Spirits"}]},{"@type":"WebSite","@id":"https:\/\/lawbelize.bz\/es\/#website","url":"https:\/\/lawbelize.bz\/es\/","name":"Wrobel &amp; Co. Belize Attorneys at-law","description":"Belize Lawyers | Belize Law Firm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lawbelize.bz\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lawbelize.bz\/es\/#\/schema\/person\/1747b4198dbf405d0ec6cc0f6bcd14c8","name":"James Miller","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62ac1264ad7235785b0d86c0cb9c7c13612e5d6f413d9cb4da00f26c50a75a0a?s=96&d=mm&r=g","caption":"James Miller"},"url":"https:\/\/lawbelize.bz\/es\/author\/james\/"}]}},"_links":{"self":[{"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/posts\/5341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/comments?post=5341"}],"version-history":[{"count":2,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/posts\/5341\/revisions"}],"predecessor-version":[{"id":5343,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/posts\/5341\/revisions\/5343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/media\/5307"}],"wp:attachment":[{"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/media?parent=5341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/categories?post=5341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lawbelize.bz\/es\/wp-json\/wp\/v2\/tags?post=5341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}